{"id":691,"date":"2026-06-02T19:48:38","date_gmt":"2026-06-02T19:48:38","guid":{"rendered":"https:\/\/phare-global.online\/?page_id=691"},"modified":"2026-06-10T23:07:53","modified_gmt":"2026-06-10T23:07:53","slug":"home-2","status":"publish","type":"page","link":"https:\/\/staging.phare-global.online\/fr\/","title":{"rendered":"home 2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"691\" class=\"elementor elementor-691 elementor-115\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d40faa1 e-flex e-con-boxed e-con e-parent\" data-id=\"d40faa1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d4a7e4d e-con-full e-flex e-con e-child\" data-id=\"d4a7e4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-83cf956 e-con-full e-flex e-con e-child\" data-id=\"83cf956\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62b7f1e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"62b7f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conectamos las necesidades del territorio con oportunidades globales que generan impacto.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef3c5b0 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"ef3c5b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Somos una organizaci\u00f3n eurolatinoamericana sin fines de lucro integrada por profesionales que han trabajado dentro de gobiernos, redes internacionales, organismos multilaterales y espacios de cooperaci\u00f3n.<\/p><p>Venimos de la pr\u00e1ctica. De la gesti\u00f3n. De acompa\u00f1ar decisiones, construir alianzas, negociar agendas e implementar proyectos en contextos reales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a236dc5 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"a236dc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-691","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>home 2 - PHARE \u2013 Territorios Globales<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"home 2 - PHARE \u2013 Territorios Globales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.phare-global.online\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"PHARE \u2013 Territorios Globales\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T23:07:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/\",\"url\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/\",\"name\":\"home 2 - PHARE \u2013 Territorios Globales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#website\"},\"datePublished\":\"2026-06-02T19:48:38+00:00\",\"dateModified\":\"2026-06-10T23:07:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"home 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/\",\"name\":\"PHARE \u2013 Territorios Globales\",\"description\":\"Promovemos la internacionalizaci\u00f3n de los gobiernos locales a trav\u00e9s de pol\u00edticas estrat\u00e9gicas de vinculaci\u00f3n internacional\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#organization\",\"name\":\"PHARE \u2013 Territorios Globales\",\"url\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.phare-global.online\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-phare_color.svg\",\"contentUrl\":\"https:\\\/\\\/staging.phare-global.online\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-phare_color.svg\",\"width\":291,\"height\":187.8,\"caption\":\"PHARE \u2013 Territorios Globales\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.phare-global.online\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"home 2 - PHARE \u2013 Territorios Globales","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"home 2 - PHARE \u2013 Territorios Globales","og_url":"https:\/\/staging.phare-global.online\/fr\/","og_site_name":"PHARE \u2013 Territorios Globales","article_modified_time":"2026-06-10T23:07:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.phare-global.online\/fr\/","url":"https:\/\/staging.phare-global.online\/fr\/","name":"home 2 - PHARE \u2013 Territorios Globales","isPartOf":{"@id":"https:\/\/staging.phare-global.online\/fr\/#website"},"datePublished":"2026-06-02T19:48:38+00:00","dateModified":"2026-06-10T23:07:53+00:00","breadcrumb":{"@id":"https:\/\/staging.phare-global.online\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.phare-global.online\/fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.phare-global.online\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/staging.phare-global.online\/fr\/"},{"@type":"ListItem","position":2,"name":"home 2"}]},{"@type":"WebSite","@id":"https:\/\/staging.phare-global.online\/fr\/#website","url":"https:\/\/staging.phare-global.online\/fr\/","name":"PHARE \u2013 Territorios Globales","description":"Promovemos la internacionalizaci\u00f3n de los gobiernos locales a trav\u00e9s de pol\u00edticas estrat\u00e9gicas de vinculaci\u00f3n internacional","publisher":{"@id":"https:\/\/staging.phare-global.online\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.phare-global.online\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/staging.phare-global.online\/fr\/#organization","name":"PHARE \u2013 Territorios Globales","url":"https:\/\/staging.phare-global.online\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/staging.phare-global.online\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/staging.phare-global.online\/wp-content\/uploads\/2026\/05\/logo-phare_color.svg","contentUrl":"https:\/\/staging.phare-global.online\/wp-content\/uploads\/2026\/05\/logo-phare_color.svg","width":291,"height":187.8,"caption":"PHARE \u2013 Territorios Globales"},"image":{"@id":"https:\/\/staging.phare-global.online\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/pages\/691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/comments?post=691"}],"version-history":[{"count":1,"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/pages\/691\/revisions"}],"predecessor-version":[{"id":692,"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/pages\/691\/revisions\/692"}],"wp:attachment":[{"href":"https:\/\/staging.phare-global.online\/fr\/wp-json\/wp\/v2\/media?parent=691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}